{"id":4771,"date":"2021-03-05T15:48:00","date_gmt":"2021-03-05T14:48:00","guid":{"rendered":"https:\/\/solori.it\/?p=4771"},"modified":"2026-03-09T14:38:24","modified_gmt":"2026-03-09T13:38:24","slug":"affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento","status":"publish","type":"post","link":"https:\/\/solori.it\/en\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/","title":{"rendered":"Affidamento del servizio di stampa degli avvisi di pagamento"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Determinazione con impegno di spesa inerente all\u2019affidamento diretto del servizio di stampa degli avvisi di pagamento<br><strong>CIG: Z5030DEC7E<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Scaduto il 12\/03\/2021<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/moduli.solori.it\/pdf\/gare\/Rideterminazione_impegno_di_spesa.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Rideterminazione impegno di spesa<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/moduli.solori.it\/pdf\/gare\/capitolato-servizio-di-servizio-di-stampa-degli-avvisi-di-pagamento.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Capitolato servizio di stampa<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/moduli.solori.it\/pdf\/gare\/determina-di-affidamento-diretto-del-servizio-di-stampa-degli-avvisi-di-pagamento.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Determina di affidamento diretto<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/moduli.solori.it\/pdf\/gare\/disciplinare-servizio-di-stampa-degli-avvisi-di-pagamento.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Disciplinare servizio di stampa<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Determinazione con impegno di spesa inerente all\u2019affidamento diretto del servizio di stampa degli avvisi di pagamentoCIG: Z5030DEC7E Scaduto il 12\/03\/2021 Rideterminazione impegno di spesa Capitolato servizio di stampa Determina di affidamento diretto Disciplinare servizio di stampa<\/p>","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[185],"tags":[],"class_list":["post-4771","post","type-post","status-publish","format-standard","hentry","category-bandi-e-gare-2021","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Affidamento del servizio di stampa degli avvisi di pagamento - Solori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solori.it\/en\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affidamento del servizio di stampa degli avvisi di pagamento - Solori\" \/>\n<meta property=\"og:description\" content=\"Determinazione con impegno di spesa inerente all\u2019affidamento diretto del servizio di stampa degli avvisi di pagamentoCIG: Z5030DEC7E Scaduto il 12\/03\/2021 Rideterminazione impegno di spesa Capitolato servizio di stampa Determina di affidamento diretto Disciplinare servizio di stampa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solori.it\/en\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Solori\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-05T14:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T13:38:24+00:00\" \/>\n<meta name=\"author\" content=\"Solori\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solori\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/\"},\"author\":{\"name\":\"Solori\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/person\\\/2a3c5b97ad66c353123a4972bd45e6d9\"},\"headline\":\"Affidamento del servizio di stampa degli avvisi di pagamento\",\"datePublished\":\"2021-03-05T14:48:00+00:00\",\"dateModified\":\"2026-03-09T13:38:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\"},\"articleSection\":[\"Bandi e gare 2021\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/\",\"url\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/\",\"name\":\"Affidamento del servizio di stampa degli avvisi di pagamento - Solori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#website\"},\"datePublished\":\"2021-03-05T14:48:00+00:00\",\"dateModified\":\"2026-03-09T13:38:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solori.it\\\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affidamento del servizio di stampa degli avvisi di pagamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solori.it\\\/#website\",\"url\":\"https:\\\/\\\/solori.it\\\/\",\"name\":\"Solori\",\"description\":\"Societ\u00e0 locale di riscossione\",\"publisher\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\",\"name\":\"Solori\",\"url\":\"https:\\\/\\\/solori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solori.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-sfondo-bianco.jpg\",\"contentUrl\":\"https:\\\/\\\/solori.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-sfondo-bianco.jpg\",\"width\":527,\"height\":216,\"caption\":\"Solori\"},\"image\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/person\\\/2a3c5b97ad66c353123a4972bd45e6d9\",\"name\":\"Solori\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g\",\"caption\":\"Solori\"},\"url\":\"https:\\\/\\\/solori.it\\\/en\\\/author\\\/apfelstrudel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Affidamento del servizio di stampa degli avvisi di pagamento - Solori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solori.it\/en\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/","og_locale":"en_GB","og_type":"article","og_title":"Affidamento del servizio di stampa degli avvisi di pagamento - Solori","og_description":"Determinazione con impegno di spesa inerente all\u2019affidamento diretto del servizio di stampa degli avvisi di pagamentoCIG: Z5030DEC7E Scaduto il 12\/03\/2021 Rideterminazione impegno di spesa Capitolato servizio di stampa Determina di affidamento diretto Disciplinare servizio di stampa","og_url":"https:\/\/solori.it\/en\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/","og_site_name":"Solori","article_published_time":"2021-03-05T14:48:00+00:00","article_modified_time":"2026-03-09T13:38:24+00:00","author":"Solori","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Solori"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/#article","isPartOf":{"@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/"},"author":{"name":"Solori","@id":"https:\/\/solori.it\/#\/schema\/person\/2a3c5b97ad66c353123a4972bd45e6d9"},"headline":"Affidamento del servizio di stampa degli avvisi di pagamento","datePublished":"2021-03-05T14:48:00+00:00","dateModified":"2026-03-09T13:38:24+00:00","mainEntityOfPage":{"@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/"},"wordCount":48,"publisher":{"@id":"https:\/\/solori.it\/#organization"},"articleSection":["Bandi e gare 2021"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/","url":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/","name":"Affidamento del servizio di stampa degli avvisi di pagamento - Solori","isPartOf":{"@id":"https:\/\/solori.it\/#website"},"datePublished":"2021-03-05T14:48:00+00:00","dateModified":"2026-03-09T13:38:24+00:00","breadcrumb":{"@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solori.it\/affidamento-del-servizio-di-stampa-degli-avvisi-di-pagamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solori.it\/"},{"@type":"ListItem","position":2,"name":"Affidamento del servizio di stampa degli avvisi di pagamento"}]},{"@type":"WebSite","@id":"https:\/\/solori.it\/#website","url":"https:\/\/solori.it\/","name":"Solori","description":"Societ\u00e0 locale di riscossione","publisher":{"@id":"https:\/\/solori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/solori.it\/#organization","name":"Solori","url":"https:\/\/solori.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/solori.it\/#\/schema\/logo\/image\/","url":"https:\/\/solori.it\/wp-content\/uploads\/2024\/08\/logo-sfondo-bianco.jpg","contentUrl":"https:\/\/solori.it\/wp-content\/uploads\/2024\/08\/logo-sfondo-bianco.jpg","width":527,"height":216,"caption":"Solori"},"image":{"@id":"https:\/\/solori.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solori.it\/#\/schema\/person\/2a3c5b97ad66c353123a4972bd45e6d9","name":"Solori","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2fec541cf28196dc8b999d2ef5c6c83bedfe669d306ad3af543a99ea139cb8?s=96&d=mm&r=g","caption":"Solori"},"url":"https:\/\/solori.it\/en\/author\/apfelstrudel\/"}]}},"_links":{"self":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts\/4771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/comments?post=4771"}],"version-history":[{"count":0,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts\/4771\/revisions"}],"wp:attachment":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/media?parent=4771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/categories?post=4771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/tags?post=4771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}