{"id":3183,"date":"2023-03-16T18:36:00","date_gmt":"2023-03-16T17:36:00","guid":{"rendered":"https:\/\/solori.it\/?p=3183"},"modified":"2026-03-09T14:37:08","modified_gmt":"2026-03-09T13:37:08","slug":"indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi","status":"publish","type":"post","link":"https:\/\/solori.it\/en\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/","title":{"rendered":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Avviso esplorativo di indagine di mercato per l\u2018acquisizione delle manifestazioni di interesse a partecipare alla procedura ex art. 36 comma 2 lett, a) d.lgs. 50\/2016 smi per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi, ai sensi dell\u2019art.14 del d.lgs.27 gennaio 2010 n.39<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/solori.it\/wp-content\/uploads\/2023\/03\/INDAGINE_DI_MERCATO_PER_REVISIONE_LEGALE.pdf\">Indagine di mercato<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Avviso esplorativo di indagine di mercato per l\u2018acquisizione delle manifestazioni di interesse a partecipare alla procedura ex art. 36 comma 2 lett, a) d.lgs. 50\/2016 smi per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi, ai sensi dell\u2019art.14 del d.lgs.27 gennaio 2010 n.39 Indagine di mercato<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[131],"tags":[],"class_list":["post-3183","post","type-post","status-publish","format-standard","hentry","category-bandi-e-gare-2023","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solori.it\/en\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori\" \/>\n<meta property=\"og:description\" content=\"Avviso esplorativo di indagine di mercato per l\u2018acquisizione delle manifestazioni di interesse a partecipare alla procedura ex art. 36 comma 2 lett, a) d.lgs. 50\/2016 smi per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi, ai sensi dell\u2019art.14 del d.lgs.27 gennaio 2010 n.39 Indagine di mercato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solori.it\/en\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/\" \/>\n<meta property=\"og:site_name\" content=\"Solori\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T17:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T13:37:08+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/person\\\/554d527b120a40cbfbb5e5b352d27936\"},\"headline\":\"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi\",\"datePublished\":\"2023-03-16T17:36:00+00:00\",\"dateModified\":\"2026-03-09T13:37:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/\"},\"wordCount\":76,\"publisher\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\"},\"articleSection\":[\"Bandi e gare 2023\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/\",\"url\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/\",\"name\":\"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#website\"},\"datePublished\":\"2023-03-16T17:36:00+00:00\",\"dateModified\":\"2026-03-09T13:37:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solori.it\\\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solori.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solori.it\\\/#website\",\"url\":\"https:\\\/\\\/solori.it\\\/\",\"name\":\"Solori\",\"description\":\"Societ\u00e0 locale di riscossione\",\"publisher\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solori.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solori.it\\\/#organization\",\"name\":\"Solori\",\"url\":\"https:\\\/\\\/solori.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solori.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-sfondo-bianco.jpg\",\"contentUrl\":\"https:\\\/\\\/solori.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-sfondo-bianco.jpg\",\"width\":527,\"height\":216,\"caption\":\"Solori\"},\"image\":{\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solori.it\\\/#\\\/schema\\\/person\\\/554d527b120a40cbfbb5e5b352d27936\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/solori.it\\\/wp-quick-install\\\/index.php\"],\"url\":\"https:\\\/\\\/solori.it\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solori.it\/en\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/","og_locale":"en_GB","og_type":"article","og_title":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori","og_description":"Avviso esplorativo di indagine di mercato per l\u2018acquisizione delle manifestazioni di interesse a partecipare alla procedura ex art. 36 comma 2 lett, a) d.lgs. 50\/2016 smi per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi, ai sensi dell\u2019art.14 del d.lgs.27 gennaio 2010 n.39 Indagine di mercato","og_url":"https:\/\/solori.it\/en\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/","og_site_name":"Solori","article_published_time":"2023-03-16T17:36:00+00:00","article_modified_time":"2026-03-09T13:37:08+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/#article","isPartOf":{"@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/"},"author":{"name":"admin","@id":"https:\/\/solori.it\/#\/schema\/person\/554d527b120a40cbfbb5e5b352d27936"},"headline":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi","datePublished":"2023-03-16T17:36:00+00:00","dateModified":"2026-03-09T13:37:08+00:00","mainEntityOfPage":{"@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/"},"wordCount":76,"publisher":{"@id":"https:\/\/solori.it\/#organization"},"articleSection":["Bandi e gare 2023"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/","url":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/","name":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi - Solori","isPartOf":{"@id":"https:\/\/solori.it\/#website"},"datePublished":"2023-03-16T17:36:00+00:00","dateModified":"2026-03-09T13:37:08+00:00","breadcrumb":{"@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solori.it\/indagine-di-mercato-per-laffidamento-del-servizio-di-revisione-legale-dei-conti-di-solori-spa-e-di-altri-servizi-connessi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solori.it\/"},{"@type":"ListItem","position":2,"name":"Indagine di mercato per l\u2019affidamento del servizio di revisione legale dei conti di Solori SPA e di altri servizi connessi"}]},{"@type":"WebSite","@id":"https:\/\/solori.it\/#website","url":"https:\/\/solori.it\/","name":"Solori","description":"Societ\u00e0 locale di riscossione","publisher":{"@id":"https:\/\/solori.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solori.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/solori.it\/#organization","name":"Solori","url":"https:\/\/solori.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/solori.it\/#\/schema\/logo\/image\/","url":"https:\/\/solori.it\/wp-content\/uploads\/2024\/08\/logo-sfondo-bianco.jpg","contentUrl":"https:\/\/solori.it\/wp-content\/uploads\/2024\/08\/logo-sfondo-bianco.jpg","width":527,"height":216,"caption":"Solori"},"image":{"@id":"https:\/\/solori.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solori.it\/#\/schema\/person\/554d527b120a40cbfbb5e5b352d27936","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2609bb79b1d65ad7884baf65bee12afb2555012392b6816136707c46af3dcefd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/solori.it\/wp-quick-install\/index.php"],"url":"https:\/\/solori.it\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts\/3183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/comments?post=3183"}],"version-history":[{"count":0,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/posts\/3183\/revisions"}],"wp:attachment":[{"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/media?parent=3183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/categories?post=3183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solori.it\/en\/wp-json\/wp\/v2\/tags?post=3183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}